{"id":967,"date":"2022-11-06T00:27:45","date_gmt":"2022-11-06T03:27:45","guid":{"rendered":"https:\/\/musashi.com.br\/jornal\/?p=967"},"modified":"2022-11-07T16:23:45","modified_gmt":"2022-11-07T19:23:45","slug":"campanha-solidaria-a-caridade-e-um-ato-revolucionario","status":"publish","type":"post","link":"https:\/\/musashi.com.br\/jornal\/campanha-solidaria-a-caridade-e-um-ato-revolucionario\/","title":{"rendered":"Campanha solid\u00e1ria: A caridade \u00e9 um ato revolucion\u00e1rio"},"content":{"rendered":"<p>A Musashi \u00e9 uma empresa que se preocupa com as pessoas ao seu redor, por isso, em parceria com seus colaboradores, promoveu em outubro uma campanha solid\u00e1ria para arrecada\u00e7\u00e3o de donativos em benef\u00edcio da Associa\u00e7\u00e3o Banho de Cidadania Recife (@banhorecife). A ONG atua na Regi\u00e3o Metropolitana realizando a\u00e7\u00f5es semanais de acolhimento a pessoas em situa\u00e7\u00e3o de rua.<\/p>\n<p>Todas as quartas feiras a Associa\u00e7\u00e3o se dirige a diferentes pontos da regi\u00e3o permitindo que pessoas carentes tenham possibilidade de tomar banho e fazer uma refei\u00e7\u00e3o, al\u00e9m de disponibilizar corte de cabelo, doa\u00e7\u00e3o de roupas e kits de higiene pessoal.<\/p>\n<p>Foram arrecadados mais de 1800 itens de higiene pessoal, 50 toalhas e alimentos n\u00e3o perec\u00edveis. A doa\u00e7\u00e3o foi entregue a institui\u00e7\u00e3o em 21\/10, pelos representantes do grupo \u201cLa Casa Sem Papel\u201d que participou do Programa de Sustentabilidade da Honda 2022.<\/p>\n<p>A musashi tem orgulho de seus colaboradores e da sua solidariedade. Vamos continuar juntos ajudando quem mais precisa.<\/p>\n<p>Voc\u00ea pode conferir as fotos dessa grande doa\u00e7\u00e3o abaixo:<\/p>\n<div id='gallery_1' class='gallery galleryid-967 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n                <div class='gallery-icon portrait'>\n                    <a href='https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-150x150.jpg\" data-sizes=\"auto\" data-srcset=\"https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-150x150.jpg 150w, https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-75x75.jpg 75w, https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-350x350.jpg 350w\" data-expand=\"700\" \/><\/a>\n                <\/div><\/figure><figure class='gallery-item'>\n                <div class='gallery-icon portrait'>\n                    <a href='https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-5.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-5-150x150.jpg\" data-sizes=\"auto\" data-srcset=\"https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-5-150x150.jpg 150w, https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-5-75x75.jpg 75w, https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-5-350x350.jpg 350w\" data-expand=\"700\" \/><\/a>\n                <\/div><\/figure><figure class='gallery-item'>\n                <div class='gallery-icon landscape'>\n                    <a href='https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-4-150x150.jpg\" data-sizes=\"auto\" data-srcset=\"https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-4-150x150.jpg 150w, https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-4-75x75.jpg 75w, https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-4-350x350.jpg 350w\" data-expand=\"700\" \/><\/a>\n                <\/div><\/figure><br style=\"clear: both\" \/><figure class='gallery-item'>\n                <div class='gallery-icon landscape'>\n                    <a href='https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-3.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-3-150x150.jpeg\" data-sizes=\"auto\" data-srcset=\"https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-3-150x150.jpeg 150w, https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-3-75x75.jpeg 75w, https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-3-350x350.jpeg 350w\" data-expand=\"700\" \/><\/a>\n                <\/div><\/figure><figure class='gallery-item'>\n                <div class='gallery-icon landscape'>\n                    <a href='https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-2.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-2-150x150.jpeg\" data-sizes=\"auto\" data-srcset=\"https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-2-150x150.jpeg 150w, https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-2-75x75.jpeg 75w, https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-2-350x350.jpeg 350w\" data-expand=\"700\" \/><\/a>\n                <\/div><\/figure><figure class='gallery-item'>\n                <div class='gallery-icon portrait'>\n                    <a href='https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-1.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-1-150x150.jpeg\" data-sizes=\"auto\" data-srcset=\"https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-1-150x150.jpeg 150w, https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-1-75x75.jpeg 75w, https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2022\/11\/camp-out-1-350x350.jpeg 350w\" data-expand=\"700\" \/><\/a>\n                <\/div><\/figure><br style=\"clear: both\" \/>\n            <\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>A Musashi \u00e9 uma empresa que se preocupa com as pessoas ao seu redor, por isso, em parceria com seus colaboradores, promoveu em outubro uma campanha solid\u00e1ria para arrecada\u00e7\u00e3o de donativos em benef\u00edcio da Associa\u00e7\u00e3o Banho de Cidadania Recife (@banhorecife). A ONG atua na Regi\u00e3o Metropolitana realizando a\u00e7\u00f5es semanais de acolhimento a pessoas em situa\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":965,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jnews-multi-image_gallery":[],"jnews_single_post":{"source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"3","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"0","show_view_counter":"0","show_featured":"1","show_post_meta":"1","show_post_author":"0","show_post_author_image":"0","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"0","number_popup_post":"1","show_author_box":"0","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[22],"tags":[128],"class_list":["post-967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","tag-campanha"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts\/967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=967"}],"version-history":[{"count":2,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts\/967\/revisions"}],"predecessor-version":[{"id":1011,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts\/967\/revisions\/1011"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/media\/965"}],"wp:attachment":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}