{"id":899,"date":"2022-10-05T09:53:17","date_gmt":"2022-10-05T12:53:17","guid":{"rendered":"https:\/\/musashi.com.br\/jornal\/?p=899"},"modified":"2022-10-05T09:53:17","modified_gmt":"2022-10-05T12:53:17","slug":"saiba-como-se-prevenir-da-esteatose-hepatica","status":"publish","type":"post","link":"https:\/\/musashi.com.br\/jornal\/saiba-como-se-prevenir-da-esteatose-hepatica\/","title":{"rendered":"Saiba como se prevenir da esteatose hep\u00e1tica!"},"content":{"rendered":"<p>A esteatose vem se tornando uma doen\u00e7a do f\u00edgado cada vez mais conhecida da popula\u00e7\u00e3o em geral. Esse fato se deve \u00e0 maior disponibilidade para realiza\u00e7\u00e3o de ultrassonografias de abd\u00f4men, exame de imagem que pode mostrar a esteatose e tem sido realizado com frequ\u00eancia em avalia\u00e7\u00f5es cl\u00ednicas de rotina,e a crescente preval\u00eancia da obesidade em todo o mundo, que \u00e9 uma das suas principais causas.<\/p>\n<p>Esta doen\u00e7a caracteriza-se pelo ac\u00famulo excessivo de gordura (lip\u00eddios) nas c\u00e9lulas do f\u00edgado denominadas hepat\u00f3citos. Essa pode permanecer est\u00e1vel por muitos anos e at\u00e9 regredir, se suas causas forem controladas. Se n\u00e3o o forem, a doen\u00e7a pode evoluir para a esteatoepatite. Nessa fase a esteatose se associa a inflama\u00e7\u00e3o e morte celular, fibrose (cicatriza\u00e7\u00e3o) e tem maior potencial de progress\u00e3o, ao longo dos anos, para cirrose e para o carcinoma hepatocelular (CHC) ou c\u00e2ncer de f\u00edgado.<\/p>\n<p>Os principais fatores de risco ou causas de DHGNA est\u00e3o relacionados a seguir:<\/p>\n<ul>\n<li>Obesidade e sobrepeso com obesidade central;<\/li>\n<li>Diabetes mellitus;<\/li>\n<li>Dislipidemia (aumento do colesterol e\/ou triglic\u00e9rides);<\/li>\n<li>Hipertens\u00e3o arterial<\/li>\n<\/ul>\n<p>Ela \u00e9 considerada a mais frequente doen\u00e7a de f\u00edgado da atualidade. Estima-se que entre 20 a 30% da popula\u00e7\u00e3o em todo o mundo seja portadora da DHGNA, ela pode ocorrer em homens e mulheres de todas as idades. o que tamb\u00e9m preocupa \u00e9 a associa\u00e7\u00e3o da DHGNA, quando n\u00e3o controlada, com a maior frequ\u00eancia de diabetes e hipertens\u00e3o arterial e com o maior risco de doen\u00e7as cardiovasculares (infarto do mioc\u00e1rdio e acidente vascular cerebral).<\/p>\n<p>A grande maioria dos pacientes n\u00e3o apresentam sinais ou sintomas, pois esta \u00e9 uma doen\u00e7a silenciosa. O progn\u00f3stico pode ser bom, mas depende da fase em que a doen\u00e7a for diagnosticada e principalmente da ader\u00eancia dos pacientes \u00e0s condutas cl\u00ednicas e tratamentos recomendados. Entendeu? Sua sa\u00fade e bem estar s\u00e3o muito importantes para n\u00f3s! Olho na sa\u00fade!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A esteatose vem se tornando uma doen\u00e7a do f\u00edgado cada vez mais conhecida da popula\u00e7\u00e3o em geral. Esse fato se deve \u00e0 maior disponibilidade para realiza\u00e7\u00e3o de ultrassonografias de abd\u00f4men, exame de imagem que pode mostrar a esteatose e tem sido realizado com frequ\u00eancia em avalia\u00e7\u00f5es cl\u00ednicas de rotina,e a crescente preval\u00eancia da obesidade em [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":900,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jnews-multi-image_gallery":[],"jnews_single_post":{"source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"3","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"0","show_view_counter":"0","show_featured":"1","show_post_meta":"1","show_post_author":"0","show_post_author_image":"0","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"0","number_popup_post":"1","show_author_box":"0","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":""},"jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[19],"tags":[67,120],"class_list":["post-899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude","tag-dicas-de-saude","tag-esteatose-hepatica"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts\/899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=899"}],"version-history":[{"count":1,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts\/899\/revisions"}],"predecessor-version":[{"id":901,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts\/899\/revisions\/901"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/media\/900"}],"wp:attachment":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}