{"id":2195,"date":"2023-10-11T10:14:24","date_gmt":"2023-10-11T13:14:24","guid":{"rendered":"https:\/\/musashi.com.br\/jornal\/?p=2195"},"modified":"2023-10-14T07:46:31","modified_gmt":"2023-10-14T10:46:31","slug":"musashi-do-brasil-celebra-o-aniversario-da-cidade-de-igarassu","status":"publish","type":"post","link":"https:\/\/musashi.com.br\/jornal\/musashi-do-brasil-celebra-o-aniversario-da-cidade-de-igarassu\/","title":{"rendered":"Musashi do Brasil celebra o anivers\u00e1rio da cidade de Igarassu"},"content":{"rendered":"<p>O dia 27 de Setembro foi marcado pelo anivers\u00e1rio de nossa querida cidade de Igarassu, que completa mais um ano de hist\u00f3ria, cultura e crescimento. Para n\u00f3s, Igarassu \u00e9 mais do que apenas o local onde nossa empresa est\u00e1 sediada; \u00e9 nossa casa e parte integrante de nossa identidade.<\/p>\n<p>Fundada em 1537, Igarassu \u00e9 uma das cidades mais antigas do Brasil, com um rico patrim\u00f4nio hist\u00f3rico e cultural. Suas praias deslumbrantes, igrejas centen\u00e1rias e o famoso Convento de S\u00e3o Francisco fazem parte do cen\u00e1rio que torna Igarassu t\u00e3o especial.<\/p>\n<p>Ao longo dos anos, nossa rela\u00e7\u00e3o com a comunidade Igarassuense cresceu e se fortaleceu. Juntos, compartilhamos n\u00e3o apenas o compromisso com a excel\u00eancia em nossas opera\u00e7\u00f5es, mas tamb\u00e9m o orgulho de fazer parte desta cidade t\u00e3o especial.<\/p>\n<p>Expressamos toda nossa gratid\u00e3o \u00e0 cidade de Igarassu e a todos os seus habitantes. A Musashi do Brasil se sente honrada por fazer parte desta comunidade \u00fanica e diversificada.<\/p>\n<p>Nossa empresa continuar\u00e1 a trabalhar em estreita parceria com a cidade que chamamos de casa, comprometida com o desenvolvimento e a melhoria da qualidade de vida de todos os seus moradores.<\/p>\n<p>Parab\u00e9ns, Igarassu, pelo seu anivers\u00e1rio! Que os pr\u00f3ximos anos sejam de ainda mais crescimento, prosperidade e uni\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O dia 27 de Setembro foi marcado pelo anivers\u00e1rio de nossa querida cidade de Igarassu, que completa mais um ano de hist\u00f3ria, cultura e crescimento. Para n\u00f3s, Igarassu \u00e9 mais do que apenas o local onde nossa empresa est\u00e1 sediada; \u00e9 nossa casa e parte integrante de nossa identidade. Fundada em 1537, Igarassu \u00e9 uma [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jnews-multi-image_gallery":[],"jnews_single_post":{"source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"0","show_view_counter":"0","show_featured":"1","show_post_meta":"1","show_post_author":"0","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"0","show_popup_post":"0","number_popup_post":"1","show_author_box":"0","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[12],"tags":[155,237],"class_list":["post-2195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-aniversario","tag-igarassu"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts\/2195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=2195"}],"version-history":[{"count":3,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts\/2195\/revisions"}],"predecessor-version":[{"id":2279,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts\/2195\/revisions\/2279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/media\/2226"}],"wp:attachment":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=2195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=2195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=2195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}