{"id":2027,"date":"2023-08-09T13:45:26","date_gmt":"2023-08-09T16:45:26","guid":{"rendered":"https:\/\/musashi.com.br\/jornal\/?p=2027"},"modified":"2023-08-09T13:45:26","modified_gmt":"2023-08-09T16:45:26","slug":"semana-da-parceria-educacional-fortalecendo-lacos-com-instituicoes-de-graduacao-e-idiomas-para-o-desenvolvimento-dos-colaboradores","status":"publish","type":"post","link":"https:\/\/musashi.com.br\/jornal\/semana-da-parceria-educacional-fortalecendo-lacos-com-instituicoes-de-graduacao-e-idiomas-para-o-desenvolvimento-dos-colaboradores\/","title":{"rendered":"Semana da Parceria Educacional: fortalecendo la\u00e7os com institui\u00e7\u00f5es de gradua\u00e7\u00e3o e idiomas para o desenvolvimento dos colaboradores"},"content":{"rendered":"<p>A Musashi do Brasil promoveu a &#8220;Semana da Parceria Educacional&#8221;. O evento reuniu as institui\u00e7\u00f5es de gradua\u00e7\u00e3o e idiomas conveniadas com a empresa, entre elas estavam: CNA, UNINASSAU, UNIBRA, ETP e FACIG. O evento serviu para estreitar os la\u00e7os e oferecer aos colaboradores e dependentes da nossa empresa oportunidades \u00fanicas de crescimento pessoal e profissional.<\/p>\n<p>Durante a semana, as institui\u00e7\u00f5es parceiras se uniram \u00e0 Musashi do Brasil para proporcionar aos colaboradores um ambiente de intera\u00e7\u00e3o com o intuito de sanar d\u00favidas e apresentar as op\u00e7\u00f5es de cursos e programas dispon\u00edveis. Essa iniciativa reflete o compromisso da empresa em investir no desenvolvimento cont\u00ednuo de seus talentos, promovendo uma cultura de aprendizado e crescimento.<br \/>\nOs colaboradores tiveram a oportunidade de interagir diretamente com representantes das institui\u00e7\u00f5es de ensino que estavam dispon\u00edveis para esclarecer quest\u00f5es sobre cursos de gradua\u00e7\u00e3o, p\u00f3s-gradua\u00e7\u00e3o e programas de idiomas.<\/p>\n<p>Uma das grandes vantagens da &#8220;Semana da Parceria Educacional&#8221; foi a possibilidade de obter descontos exclusivos nos cursos oferecidos pelas institui\u00e7\u00f5es conveniadas. Esse benef\u00edcio refor\u00e7a o compromisso da Musashi do Brasil em apoiar seus colaboradores em sua jornada educacional e profissional, tornando a busca pelo conhecimento mais acess\u00edvel e estimulante.<\/p>\n<p>A valoriza\u00e7\u00e3o da educa\u00e7\u00e3o \u00e9 uma das premissas da MSB, que acredita que investir no aprendizado cont\u00ednuo de seus colaboradores \u00e9 um dos principais pilares para o crescimento e sucesso da empresa. Ao fortalecer parcerias estrat\u00e9gicas com institui\u00e7\u00f5es reconhecidas no mercado educacional, a empresa reafirma seu compromisso em proporcionar aos colaboradores oportunidades de desenvolvimento alinhadas \u00e0s suas aspira\u00e7\u00f5es profissionais.<\/p>\n<div id='gallery_1' class='gallery galleryid-2027 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n                <div class='gallery-icon landscape'>\n                    <a href='https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-07-20-at-11.39.57.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-07-20-at-11.39.57-150x150.jpg\" data-sizes=\"auto\" data-srcset=\"https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-07-20-at-11.39.57-150x150.jpg 150w, https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-07-20-at-11.39.57-75x75.jpg 75w, https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-07-20-at-11.39.57-350x350.jpg 350w\" data-expand=\"700\" \/><\/a>\n                <\/div><\/figure><figure class='gallery-item'>\n                <div class='gallery-icon landscape'>\n                    <a href='https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-07-21-at-10.36.03.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-07-21-at-10.36.03-150x150.jpg\" data-sizes=\"auto\" data-srcset=\"https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-07-21-at-10.36.03-150x150.jpg 150w, https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-07-21-at-10.36.03-75x75.jpg 75w, https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-07-21-at-10.36.03-350x350.jpg 350w\" data-expand=\"700\" \/><\/a>\n                <\/div><\/figure><figure class='gallery-item'>\n                <div class='gallery-icon landscape'>\n                    <a href='https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-07-26-at-11.29.08.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-src=\"https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-07-26-at-11.29.08-150x150.jpg\" data-sizes=\"auto\" data-srcset=\"https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-07-26-at-11.29.08-150x150.jpg 150w, https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-07-26-at-11.29.08-75x75.jpg 75w, https:\/\/musashi.com.br\/jornal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-07-26-at-11.29.08-350x350.jpg 350w\" data-expand=\"700\" \/><\/a>\n                <\/div><\/figure><br style=\"clear: both\" \/>\n            <\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>A Musashi do Brasil promoveu a &#8220;Semana da Parceria Educacional&#8221;. O evento reuniu as institui\u00e7\u00f5es de gradua\u00e7\u00e3o e idiomas conveniadas com a empresa, entre elas estavam: CNA, UNINASSAU, UNIBRA, ETP e FACIG. O evento serviu para estreitar os la\u00e7os e oferecer aos colaboradores e dependentes da nossa empresa oportunidades \u00fanicas de crescimento pessoal e profissional. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2028,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jnews-multi-image_gallery":[],"jnews_single_post":{"source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"0","show_view_counter":"0","show_featured":"1","show_post_meta":"1","show_post_author":"0","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"0","show_popup_post":"0","number_popup_post":"1","show_author_box":"0","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[22],"tags":[221],"class_list":["post-2027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","tag-parceria-educacional"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts\/2027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=2027"}],"version-history":[{"count":1,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts\/2027\/revisions"}],"predecessor-version":[{"id":2032,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts\/2027\/revisions\/2032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/media\/2028"}],"wp:attachment":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=2027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=2027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=2027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}