{"id":1909,"date":"2023-07-10T09:53:04","date_gmt":"2023-07-10T12:53:04","guid":{"rendered":"https:\/\/musashi.com.br\/jornal\/?p=1909"},"modified":"2023-07-10T09:53:04","modified_gmt":"2023-07-10T12:53:04","slug":"entenda-quais-as-consequencias-causadas-pela-poluicao-e-a-urgencia-do-combate-ao-problema","status":"publish","type":"post","link":"https:\/\/musashi.com.br\/jornal\/entenda-quais-as-consequencias-causadas-pela-poluicao-e-a-urgencia-do-combate-ao-problema\/","title":{"rendered":"Entenda quais as consequ\u00eancias causadas pela polui\u00e7\u00e3o e a urg\u00eancia do combate ao problema."},"content":{"rendered":"<p>Como j\u00e1 temos debatido nas outras edi\u00e7\u00f5es, os seres humanos s\u00e3o os grandes respons\u00e1veis pela gera\u00e7\u00e3o da polui\u00e7\u00e3o que tem impactado negativamente no ambiente, cujas consequ\u00eancias podem ser observadas atrav\u00e9s das varia\u00e7\u00f5es clim\u00e1ticas, extin\u00e7\u00e3o de esp\u00e9cies, destrui\u00e7\u00e3o da camada de oz\u00f4nio, agravamento do efeito estufa, chuva \u00e1cida, inunda\u00e7\u00f5es, passivos ambientais cr\u00edticos, entre outras coisas horr\u00edveis.<\/p>\n<p>A polui\u00e7\u00e3o consiste na inser\u00e7\u00e3o de energia ou subst\u00e2ncias de maneira proposital ou acidental no meio ambiente, causando danos ao seu equil\u00edbrio e aos seres vivos. As fontes que causam essa polui\u00e7\u00e3o s\u00e3o chamadas de poluentes e podem ser classificadas em diferentes tipos. Como:<\/p>\n<ul>\n<li><strong>Polui\u00e7\u00e3o atmosf\u00e9rica:<\/strong> contamina\u00e7\u00e3o do ar por part\u00edculas s\u00f3lidas, l\u00edquidas e gasosas, as quais podem ser produzidos artificialmente, atrav\u00e9s das atividades humanas (ex.: CO2 emitido pelos ve\u00edculos) ou de fontes naturais;<\/li>\n<li><strong>Polui\u00e7\u00e3o da \u00e1gua:<\/strong> contamina\u00e7\u00e3o dos recursos h\u00eddricos atrav\u00e9s de elementos biol\u00f3gicos, f\u00edsicos e qu\u00edmicos, causada por vazamentos de materiais contaminantes em rios, mares e lagos, bem como pelo descarte irregular de res\u00edduos e efluentes diretamente nesses locais;<\/li>\n<li><strong>Polui\u00e7\u00e3o t\u00e9rmica:<\/strong> aumento ou diminui\u00e7\u00e3o da temperatura das \u00e1guas naturais, cuja principal causa \u00e9 a refrigera\u00e7\u00e3o ou aquecimento de usinas nucleares, centrais el\u00e9tricas e grandes f\u00e1bricas, que acabam por liberar vapores e\/ou efluentes a altas temperaturas;<\/li>\n<li><strong>Polui\u00e7\u00e3o do solo e subsolo:<\/strong> contato de res\u00edduos s\u00f3lidos, l\u00edquidos, efluentes e produtos qu\u00edmicos com a superf\u00edcie do solo que podem penetr\u00e1-lo e atingir subsolo e len\u00e7ol fre\u00e1tico. A aplica\u00e7\u00e3o indevida de pesticidas e fertilizantes na agricultura e o chorume gerado nos aterros n\u00e3o coletado e tratado adequadamente s\u00e3o exemplos agentes causadores desse tipo de contamina\u00e7\u00e3o;<\/li>\n<li><strong>Polui\u00e7\u00e3o luminosa:<\/strong> excesso de luz artificial projetada nas cidades, irradiando \u00e1reas de maneira inapropriada.<\/li>\n<\/ul>\n<p>Institu\u00eddo pela ONU em 1972, durante a Confer\u00eancia das Na\u00e7\u00f5es Unidas realizada em Estocolmo (Su\u00e9cia), o dia 05 de junho foi escolhido para chamar a aten\u00e7\u00e3o de toda popula\u00e7\u00e3o sobre as quest\u00f5es ambientais e a import\u00e2ncia da preven\u00e7\u00e3o da polui\u00e7\u00e3o e preserva\u00e7\u00e3o dos recursos naturais, visando a manuten\u00e7\u00e3o da nossa esp\u00e9cie.<\/p>\n<p>Com o objetivo de conscientizar nossos colaboradores, em alus\u00e3o a este marco do Calend\u00e1rio Ambiental, foi celebrada na Musashi, entre os dias 05\/06\/2023 e 09\/06\/23, a semana do Meio Ambiente.<\/p>\n<p>Durante este per\u00edodo foram compartilhadas v\u00e1rias pr\u00e1ticas desenvolvidas na empresa voltadas para minimiza\u00e7\u00e3o dos impactos ambientais gerados em nossas atividades. Atrav\u00e9s de uma din\u00e2mica, levantamos a seguinte quest\u00e3o para os nossos colaboradores: \u201cO que voc\u00ea faz hoje no seu dia a dia para preservar o meio ambiente?\u201d. Diversas atitudes foram compartilhadas e abaixo descrevemos algumas cita\u00e7\u00f5es para inspir\u00e1-los na pr\u00e1tica de atitudes sustent\u00e1veis:<\/p>\n<ul>\n<li>Economizar \u00e1gua e energia (acumulando roupas para lavagem da m\u00e1quina na capacidade m\u00e1xima, desligando as luzes ao sair do ambiente);<\/li>\n<li>Priorizar o uso do transporte coletivo;<\/li>\n<li>Evitar desperd\u00edcio de alimentos;<\/li>\n<li>Praticar a coleta seletiva;<\/li>\n<li>Utilizar produtos biodegrad\u00e1veis;<\/li>\n<li>Reutilizar e reaproveitar materiais para novas aplica\u00e7\u00f5es;<\/li>\n<li>Captar e utilizar \u00e1gua pluvial na limpeza da resid\u00eancia;<\/li>\n<li>Plantar uma \u00e1rvore.<\/li>\n<\/ul>\n<p>Prevenir a polui\u00e7\u00e3o \u00e9 papel de todos e qualquer a\u00e7\u00e3o, por mais simples que pare\u00e7a ser, \u00e9 o primeiro passo para atingirmos nossos resultados!<\/p>\n<p>\u201cExtraordinariedade \u00e9 o resultado de um ac\u00famulo de Ordinariedades\u201d, Yoshiharu Otsuka (Fundador Grupo Musashi).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como j\u00e1 temos debatido nas outras edi\u00e7\u00f5es, os seres humanos s\u00e3o os grandes respons\u00e1veis pela gera\u00e7\u00e3o da polui\u00e7\u00e3o que tem impactado negativamente no ambiente, cujas consequ\u00eancias podem ser observadas atrav\u00e9s das varia\u00e7\u00f5es clim\u00e1ticas, extin\u00e7\u00e3o de esp\u00e9cies, destrui\u00e7\u00e3o da camada de oz\u00f4nio, agravamento do efeito estufa, chuva \u00e1cida, inunda\u00e7\u00f5es, passivos ambientais cr\u00edticos, entre outras coisas horr\u00edveis. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1910,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jnews-multi-image_gallery":[],"jnews_single_post":{"source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"0","show_view_counter":"0","show_featured":"1","show_post_meta":"1","show_post_author":"0","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"0","show_popup_post":"0","number_popup_post":"1","show_author_box":"0","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[52],"tags":[201,202],"class_list":["post-1909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sustentabilidade","tag-combate","tag-poluicao"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts\/1909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=1909"}],"version-history":[{"count":1,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts\/1909\/revisions"}],"predecessor-version":[{"id":1911,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/posts\/1909\/revisions\/1911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/media\/1910"}],"wp:attachment":[{"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=1909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=1909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/musashi.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=1909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}